{"id":128330,"date":"2026-04-17T15:56:53","date_gmt":"2026-04-17T15:56:53","guid":{"rendered":"https:\/\/madame-sensuelle.paris\/product\/cache-tetons-silicone-moyen-clair-maison-close\/"},"modified":"2026-05-13T18:46:29","modified_gmt":"2026-05-13T18:46:29","slug":"cache-tetons-silicone-moyen-clair-maison-close","status":"publish","type":"product","link":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/","title":{"rendered":"Cache-t\u00e9tons silicone moyen clair Maison Close"},"content":{"rendered":"<p>Cache-t\u00e9tons en silicone couleur moyen clair Maison Close<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cache-t\u00e9tons en silicone couleur moyen clair Maison Close<\/p>\n","protected":false},"featured_media":128331,"template":"","meta":[],"pwb-brand":[3598],"product_brand":[],"product_cat":[3231,3243],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-128330","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-maison-close-2","7":"product_cat-accessories","8":"product_cat-nipple-covers","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable","16":"has-default-attributes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cache-t\u00e9tons silicone moyen clair Maison Close \u2013 MAISON CLOSE - Madame Sensuelle<\/title>\n<meta name=\"description\" content=\"Le mod\u00e8le Cache-t\u00e9tons silicone moyen clair Maison Close sign\u00e9 MAISON CLOSE, \u00e0 d\u00e9couvrir chez Madame Sensuelle. Essayage VIP disponible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cache-t\u00e9tons silicone moyen clair Maison Close \u2013 MAISON CLOSE - Madame Sensuelle\" \/>\n<meta property=\"og:description\" content=\"Le mod\u00e8le Cache-t\u00e9tons silicone moyen clair Maison Close sign\u00e9 MAISON CLOSE, \u00e0 d\u00e9couvrir chez Madame Sensuelle. Essayage VIP disponible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/\" \/>\n<meta property=\"og:site_name\" content=\"Madame Sensuelle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/madamesensuelle\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T18:46:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/madame-sensuelle.paris\/wp-content\/uploads\/2024\/12\/logo_a-1-1_16-9-_1_.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/product\\\/cache-tetons-silicone-moyen-clair-maison-close\\\/\",\"url\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/product\\\/cache-tetons-silicone-moyen-clair-maison-close\\\/\",\"name\":\"Cache-t\u00e9tons silicone moyen clair Maison Close \u2013 MAISON CLOSE - Madame Sensuelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/product\\\/cache-tetons-silicone-moyen-clair-maison-close\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/product\\\/cache-tetons-silicone-moyen-clair-maison-close\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/madame-sensuelle.paris\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/XSHD1TJ63322-scaled.webp\",\"datePublished\":\"2026-04-17T15:56:53+00:00\",\"dateModified\":\"2026-05-13T18:46:29+00:00\",\"description\":\"Le mod\u00e8le Cache-t\u00e9tons silicone moyen clair Maison Close sign\u00e9 MAISON CLOSE, \u00e0 d\u00e9couvrir chez Madame Sensuelle. Essayage VIP disponible.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/product\\\/cache-tetons-silicone-moyen-clair-maison-close\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/product\\\/cache-tetons-silicone-moyen-clair-maison-close\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/product\\\/cache-tetons-silicone-moyen-clair-maison-close\\\/#primaryimage\",\"url\":\"https:\\\/\\\/madame-sensuelle.paris\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/XSHD1TJ63322-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/madame-sensuelle.paris\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/XSHD1TJ63322-scaled.webp\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/product\\\/cache-tetons-silicone-moyen-clair-maison-close\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acceuil\",\"item\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalog\",\"item\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/catalogue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cache-t\u00e9tons silicone moyen clair Maison Close\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/\",\"name\":\"MADAME SENSUELLE\",\"description\":\"MADAME SENSUELLE: Found the biggest exciting brands of chic &amp; SEXY LINGERIE in Paris Boutique and on the WEB: Aubade, Dita Von Teese, Maison Close, Marjolaine, Bluebella, Atelier Amour, Luxxa, Catanzaro, Gracija Rim. You will found the big pleasure of sexy belt or bra make for you\",\"publisher\":{\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/#organization\",\"name\":\"Madame Sensuelle\",\"url\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/madame-sensuelle.paris\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/logo_a-1-1_696.webp\",\"contentUrl\":\"https:\\\/\\\/madame-sensuelle.paris\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/logo_a-1-1_696.webp\",\"width\":696,\"height\":696,\"caption\":\"Madame Sensuelle\"},\"image\":{\"@id\":\"https:\\\/\\\/madame-sensuelle.paris\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/madamesensuelle\",\"https:\\\/\\\/www.instagram.com\\\/madame_sensuelle\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cache-t\u00e9tons silicone moyen clair Maison Close \u2013 MAISON CLOSE - Madame Sensuelle","description":"Le mod\u00e8le Cache-t\u00e9tons silicone moyen clair Maison Close sign\u00e9 MAISON CLOSE, \u00e0 d\u00e9couvrir chez Madame Sensuelle. Essayage VIP disponible.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/","og_locale":"en_US","og_type":"article","og_title":"Cache-t\u00e9tons silicone moyen clair Maison Close \u2013 MAISON CLOSE - Madame Sensuelle","og_description":"Le mod\u00e8le Cache-t\u00e9tons silicone moyen clair Maison Close sign\u00e9 MAISON CLOSE, \u00e0 d\u00e9couvrir chez Madame Sensuelle. Essayage VIP disponible.","og_url":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/","og_site_name":"Madame Sensuelle","article_publisher":"https:\/\/www.facebook.com\/madamesensuelle","article_modified_time":"2026-05-13T18:46:29+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/madame-sensuelle.paris\/wp-content\/uploads\/2024\/12\/logo_a-1-1_16-9-_1_.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/","url":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/","name":"Cache-t\u00e9tons silicone moyen clair Maison Close \u2013 MAISON CLOSE - Madame Sensuelle","isPartOf":{"@id":"https:\/\/madame-sensuelle.paris\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/#primaryimage"},"image":{"@id":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/#primaryimage"},"thumbnailUrl":"https:\/\/madame-sensuelle.paris\/wp-content\/uploads\/2026\/04\/XSHD1TJ63322-scaled.webp","datePublished":"2026-04-17T15:56:53+00:00","dateModified":"2026-05-13T18:46:29+00:00","description":"Le mod\u00e8le Cache-t\u00e9tons silicone moyen clair Maison Close sign\u00e9 MAISON CLOSE, \u00e0 d\u00e9couvrir chez Madame Sensuelle. Essayage VIP disponible.","breadcrumb":{"@id":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/#primaryimage","url":"https:\/\/madame-sensuelle.paris\/wp-content\/uploads\/2026\/04\/XSHD1TJ63322-scaled.webp","contentUrl":"https:\/\/madame-sensuelle.paris\/wp-content\/uploads\/2026\/04\/XSHD1TJ63322-scaled.webp","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/madame-sensuelle.paris\/en\/product\/cache-tetons-silicone-moyen-clair-maison-close\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acceuil","item":"https:\/\/madame-sensuelle.paris\/en\/"},{"@type":"ListItem","position":2,"name":"Catalog","item":"https:\/\/madame-sensuelle.paris\/en\/catalogue\/"},{"@type":"ListItem","position":3,"name":"Cache-t\u00e9tons silicone moyen clair Maison Close"}]},{"@type":"WebSite","@id":"https:\/\/madame-sensuelle.paris\/en\/#website","url":"https:\/\/madame-sensuelle.paris\/en\/","name":"MADAME SENSUELLE","description":"MADAME SENSUELLE: Found the biggest exciting brands of chic &amp; SEXY LINGERIE in Paris Boutique and on the WEB: Aubade, Dita Von Teese, Maison Close, Marjolaine, Bluebella, Atelier Amour, Luxxa, Catanzaro, Gracija Rim. You will found the big pleasure of sexy belt or bra make for you","publisher":{"@id":"https:\/\/madame-sensuelle.paris\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madame-sensuelle.paris\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/madame-sensuelle.paris\/en\/#organization","name":"Madame Sensuelle","url":"https:\/\/madame-sensuelle.paris\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/madame-sensuelle.paris\/en\/#\/schema\/logo\/image\/","url":"https:\/\/madame-sensuelle.paris\/wp-content\/uploads\/2024\/12\/logo_a-1-1_696.webp","contentUrl":"https:\/\/madame-sensuelle.paris\/wp-content\/uploads\/2024\/12\/logo_a-1-1_696.webp","width":696,"height":696,"caption":"Madame Sensuelle"},"image":{"@id":"https:\/\/madame-sensuelle.paris\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/madamesensuelle","https:\/\/www.instagram.com\/madame_sensuelle\/"]}]}},"brands":[{"id":3598,"name":"MAISON CLOSE","slug":"maison-close-2"}],"_links":{"self":[{"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/product\/128330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/product\/128330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/media\/128331"}],"wp:attachment":[{"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/media?parent=128330"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/pwb-brand?post=128330"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/product_brand?post=128330"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/product_cat?post=128330"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/product_tag?post=128330"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/madame-sensuelle.paris\/en\/wp-json\/wp\/v2\/giftcard-category?post=128330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}